{"id":757,"date":"2023-06-09T09:59:35","date_gmt":"2023-06-09T09:59:35","guid":{"rendered":"https:\/\/toypek.two.prikr.space\/maatschappelijk-verantwoord-ondernemen-duurzaamheid-2\/"},"modified":"2023-07-12T10:21:27","modified_gmt":"2023-07-12T10:21:27","slug":"soziale-verantwortung","status":"publish","type":"page","link":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/","title":{"rendered":"Soziale Verantwortung und Nachhaltigkeit der Unternehmen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-757","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr<\/title>\n<meta name=\"description\" content=\"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr\" \/>\n<meta property=\"og:description\" content=\"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/\" \/>\n<meta property=\"og:site_name\" content=\"Toypek\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-12T10:21:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/\",\"url\":\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/\",\"name\":\"Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr\",\"isPartOf\":{\"@id\":\"https:\/\/toypek.two.prikr.space\/de\/#website\"},\"datePublished\":\"2023-06-09T09:59:35+00:00\",\"dateModified\":\"2023-07-12T10:21:27+00:00\",\"description\":\"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.\",\"breadcrumb\":{\"@id\":\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/toypek.two.prikr.space\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soziale Verantwortung und Nachhaltigkeit der Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/toypek.two.prikr.space\/de\/#website\",\"url\":\"https:\/\/toypek.two.prikr.space\/de\/\",\"name\":\"Toypek\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/toypek.two.prikr.space\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr","description":"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr","og_description":"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.","og_url":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/","og_site_name":"Toypek","article_modified_time":"2023-07-12T10:21:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/","url":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/","name":"Nachhaltiges Wirtschaften bei Toypek.eu! | Erfahren Sie mehr","isPartOf":{"@id":"https:\/\/toypek.two.prikr.space\/de\/#website"},"datePublished":"2023-06-09T09:59:35+00:00","dateModified":"2023-07-12T10:21:27+00:00","description":"In unserem Unternehmen glauben wir fest an unternehmerische soziale Verantwortung und Nachhaltigkeit. Im Rahmen unseres Engagements arbeiten wir mit einer Organisation namens Konnected zusammen, die sich der Schaffung von M\u00f6glichkeiten f\u00fcr Personen widmet, die vor Herausforderungen auf dem Arbeitsmarkt stehen.","breadcrumb":{"@id":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toypek.two.prikr.space\/de\/soziale-verantwortung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toypek.two.prikr.space\/de\/"},{"@type":"ListItem","position":2,"name":"Soziale Verantwortung und Nachhaltigkeit der Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/toypek.two.prikr.space\/de\/#website","url":"https:\/\/toypek.two.prikr.space\/de\/","name":"Toypek","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toypek.two.prikr.space\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/pages\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":3,"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/pages\/757\/revisions"}],"predecessor-version":[{"id":3762,"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/pages\/757\/revisions\/3762"}],"wp:attachment":[{"href":"https:\/\/toypek.two.prikr.space\/de\/wp-json\/wp\/v2\/media?parent=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}